{"id":1428,"date":"2019-02-11T14:10:20","date_gmt":"2019-02-11T13:10:20","guid":{"rendered":"https:\/\/france-ohada-droit.com\/?page_id=1428"},"modified":"2020-08-11T04:47:39","modified_gmt":"2020-08-11T02:47:39","slug":"sites-juridiques-et-financiers-en-libre-acces","status":"publish","type":"page","link":"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/","title":{"rendered":"Sites juridiques et financiers, en libre acc\u00e8s"},"content":{"rendered":"<p class=\"s10\">NDLR \u2013 Pri\u00e8re de nous informer du moindre disfonctionnement que vous pourriez constater \u00e0 l\u2019adresse\u00a0: <a href=\"mailto:france.ohada.droit@gmail.com\"><span class=\"s9\">france.ohada.droit@gmail.com<\/span><\/a><\/p>\n<p class=\"s10\">Vous pouvez \u00e9galement nous sugg\u00e9rer des sites en libre acc\u00e8s, d\u2019int\u00e9r\u00eatpour un lectorat majoritairement d\u2019Afrique francophone.<\/p>\n<p>Nous vous proposons\u00a0:<\/p>\n<div class=\"s12\"><span class=\"s11\">\u2022 <\/span>une liste g\u00e9n\u00e9rale des sites par ordre ABC\u00a0;<\/div>\n<div class=\"s14\"><span class=\"s13\">\u2713 <\/span>une liste de sites de culture et\/ou langue francophone\u00a0;<\/div>\n<div class=\"s14\"><span class=\"s13\">\u2713 <\/span>une liste de site de culture anglophone\u00a0et\/ou langue\u00a0;<\/div>\n<div class=\"s14\"><span class=\"s13\">\u2713 <\/span>et une liste de sites concernant les autres langues et cultures.<\/div>\n<p>&nbsp;<\/p>\n<p><span class=\"s2\">Liste g\u00e9n\u00e9rale des sites<\/span><span class=\"s2\"> que nous consultons le plus<\/span><span class=\"s2\">, en libre acc\u00e8s, <\/span><span class=\"s2\">par ordre ABC\u00a0<\/span><\/p>\n<div>1. <a href=\"http:\/\/www.abajournal.com\/magazine\/\"><span class=\"s15\">ABA Journal<\/span><\/a><\/div>\n<div>2. <a href=\"http:\/\/www.africanexecutive.com\/\"><span class=\"s15\">African Executive<\/span><\/a><\/div>\n<div>3. <a href=\"http:\/\/afrilex.u-bordeaux4.fr\/\"><span class=\"s15\">Afrilex<\/span><\/a><\/div>\n<div>4. <a href=\"http:\/\/afrimag.net\/\"><span class=\"s15\">Afrimag<\/span><\/a><\/div>\n<div>5. <a href=\"http:\/\/www.allchinareview.com\/\"><span class=\"s15\">All China Review<\/span><\/a><\/div>\n<div class=\"s16\">6. <a href=\"http:\/\/www.aflsf.org\/fr\"><span class=\"s9\">ALSF<\/span><\/a>, Facilit\u00e9 Africaine de Soutien Juridique (BAD)<\/div>\n<div>7. <a href=\"https:\/\/aadi.org.ar\/index.php?acc=4\"><span class=\"s15\">Anuario Argentino de Derecho Internacional<\/span><\/a><\/div>\n<div>8. <a href=\"https:\/\/digitalcommons.law.ggu.edu\/\"><span class=\"s15\">Annual Survey of International and Comparative Law<\/span><\/a><\/div>\n<div>9. <a href=\"https:\/\/aadi.org.ar\/index.php?acc=4\"><span class=\"s15\">Anuario Argentino de Derecho Internacional<\/span><\/a><\/div>\n<div>10. <a href=\"https:\/\/revistas.juridicas.unam.mx\/index.php\/derecho-internacional\"><span class=\"s15\">Anuario Mexicano de Derecho <\/span><span class=\"s15\">Internacional<\/span><\/a><\/div>\n<div class=\"s16\">11. <a href=\"https:\/\/ials.sas.ac.uk\/digital\/bailii\"><span class=\"s15\">BAILII<\/span><\/a><span class=\"s17\"> (British<\/span><span class=\"s17\"> and Irish<\/span><span class=\"s17\"> Legal Information Institute)<\/span><\/div>\n<div>12. <a href=\"http:\/\/www.uncitral.org\/uncitral\/en\/publications\/bibliography_monthly.html\"><span class=\"s15\">Bibliography related to UNCITRAL-CNUDCI <\/span><\/a><\/div>\n<div class=\"s16\">13. <a href=\"http:\/\/www.xinhuanet.com\/english\/weekly\/weekly01.htm\"><span class=\"s15\">Biz China Weekly<\/span><\/a> <span class=\"s17\">(Xinhua)<\/span><\/div>\n<div>14. <a href=\"http:\/\/juristconseil.blogspot.com\/2015\/03\/la-loi-n-10312-relative-aux.html\"><span class=\"s15\">Blog de droit <\/span><span class=\"s15\">marocain<\/span><\/a><\/div>\n<div>15. <a href=\"https:\/\/revistas.juridicas.unam.mx\/index.php\/derecho-comparado\"><span class=\"s15\">Bolet\u00edn<\/span> <span class=\"s15\">Mexicano<\/span><span class=\"s15\"> de <\/span><span class=\"s15\">Derecho<\/span> <span class=\"s15\">Comparado<\/span><\/a><\/div>\n<div>16. <a href=\"http:\/\/www.bcu.ac.uk\/law\/research\/centre-for-american-studies\/british-journal-american-legal-studies\"><span class=\"s15\">British Journal of American Legal Studies<\/span><\/a><\/div>\n<div>17. <a href=\"https:\/\/brooklynworks.brooklaw.edu\/bjil\/\"><span class=\"s15\">Brookling<\/span><span class=\"s15\"> Journal of <\/span><span class=\"s15\">Intern\u2019l<\/span><span class=\"s15\"> Law <\/span><\/a><\/div>\n<div>18. <a href=\"https:\/\/publications.banque-france.fr\/liste-chronologique\/le-bulletin-de-la-banque-de-france\"><span class=\"s15\">Bulletin de la Banque de France<\/span><\/a><\/div>\n<div class=\"s16\">19. <a href=\"https:\/\/www.courdecassation.fr\/publications_26\/bulletin_information_cour_cassation_27\/\"><span class=\"s15\">Bulletin d&#8217;information de la Cour de cassation<\/span><\/a><span class=\"s17\">, (BICC)<\/span><\/div>\n<div class=\"s16\">20. <span class=\"s17\">Cahiers de la Finance islamique<\/span><span class=\"s17\">, <\/span><a href=\"https:\/\/ribh.files.wordpress.com\/2016\/10\/les-cahier-de-la-fi-10.pdf\"><span class=\"s15\">n\u00b0 10, 2016, PDF<\/span><\/a><span class=\"s17\">\u00a0; <\/span><a href=\"https:\/\/ribh.files.wordpress.com\/2018\/10\/les-cahier-de-la-fi-11.pdf\"><span class=\"s15\">n\u00b0 11, 2018, PDF<\/span><\/a><\/div>\n<div class=\"s16\">21. <a href=\"http:\/\/www.poderjudicial.es\/cgpj\/es\/Temas\/Centro-de-Documentacion-Judicial--CENDOJ-\/\"><span class=\"s15\">Centro de Documentaci\u00f3n Judicial<\/span><\/a><span class=\"s17\"> (CENDOJ, <\/span><span class=\"s17\">Espagne<\/span><span class=\"s17\">)<\/span><\/div>\n<div>22. <a href=\"http:\/\/jtl.columbia.edu\/\"><span class=\"s15\">Columbia Journal of <\/span><span class=\"s15\">Transnat\u2019l<\/span><span class=\"s15\"> Law<\/span><\/a><\/div>\n<div>23. <a href=\"https:\/\/www.lawschool.cornell.edu\/research\/cornell-law-review\/index.cfm\"><span class=\"s15\">Cornell Law Rev.<\/span><\/a><\/div>\n<div class=\"s16\">24. <span class=\"s17\">Cour<\/span><span class=\"s17\"> penal international, <\/span><a href=\"https:\/\/www.icc-cpi.int\/Pages\/Main.aspx\"><span class=\"s18\">ICC-CPI<\/span><\/a><\/div>\n<div>25. <a href=\"https:\/\/e-revistas.uc3m.es\/index.php\/CDT\"><span class=\"s15\">Cuadernos<\/span><span class=\"s15\"> de Derecho <\/span><span class=\"s15\">Transnacional<\/span><\/a><\/div>\n<div>26. <a href=\"https:\/\/ojs.uv.es\/index.php\/CEFD\/\"><span class=\"s19\">Cuadernos Electr\u00f3nicos de Filosof\u00eda del Derecho<\/span><\/a><\/div>\n<div class=\"s12\">27. <a href=\"http:\/\/www.cubadebate.cu\/noticias\/2018\/12\/06\/trabajo-por-cuenta-propia-se-ratifican-normas-y-se-aprueban-importantes-modificaciones\/%23.XA-hyGhKiM9\"><span class=\"s9\">Cuba <\/span><span class=\"s9\">Debate<\/span><\/a><\/div>\n<div>28. <a href=\"http:\/\/www.droitbelge.be\/index.asp\"><span class=\"s15\">Droit belge<\/span><\/a><\/div>\n<div>29. <a href=\"https:\/\/www.droit-technologie.org\/\"><span class=\"s15\">Droit &amp; Technologie<\/span><\/a><\/div>\n<div>30. <a href=\"https:\/\/harvardlawreview.org\/\"><span class=\"s15\">Harvard Law Review<\/span><\/a><\/div>\n<div>31. <a href=\"http:\/\/ilreports.blogspot.com\/\"><span class=\"s15\">International Law Reporter<\/span><\/a><\/div>\n<div class=\"s16\">32. <a href=\"http:\/\/www.izf.net\/\"><span class=\"s15\">izf.net<\/span><\/a><span class=\"s17\"> (invest<\/span><span class=\"s17\">i<\/span><span class=\"s17\">r en zone Franc)<\/span><\/div>\n<div>33. <a href=\"http:\/\/www.iustel.com\/diario_del_derecho\/\"><span class=\"s19\">Iustel<\/span><span class=\"s19\"> &#8211; <\/span><span class=\"s19\">Diario<\/span> <span class=\"s19\">del<\/span> <span class=\"s19\">Derecho<\/span><\/a><\/div>\n<div>35. <a href=\"https:\/\/ribh.wordpress.com\/\"><span class=\"s15\">Journal de la finance islamique<\/span><\/a><\/div>\n<div>36. <a href=\"https:\/\/academic.oup.com\/jla\"><span class=\"s15\">Journal of Legal Analysis<\/span><\/a><\/div>\n<div class=\"s16\">37. <span class=\"s17\">Journal of Law, \u00a0Society and Development (South Africa)<\/span><span class=\"s17\">, <\/span><a href=\"https:\/\/upjournals.co.za\/index.php\/JLSD\"><span class=\"s15\">lien<\/span><\/a><\/div>\n<div class=\"s16\">38. <span class=\"s17\">Jupitec<\/span><span class=\"s17\">, <\/span><a href=\"https:\/\/www.jipitec.eu\/\"><span class=\"s15\">Jupitec<\/span><\/a><span class=\"s17\">, Intellectual Property, <\/span><span class=\"s17\">Iinformation<\/span><span class=\"s17\"> technology &amp; E-Commerce Law (RFA, online)<\/span><\/div>\n<div>39. <a href=\"http:\/\/legalref.judiciary.gov.hk\/lrs\/common\/ju\/judgment.jsp\"><span class=\"s18\">Jurisprudence de Hong Kong<\/span><\/a><\/div>\n<div>40. <a href=\"http:\/\/juspoliticum.com\/la-revue\"><span class=\"s20\">Jus <\/span><span class=\"s20\">Politicum<\/span><\/a><\/div>\n<div>41. <a href=\"https:\/\/www.legalis.net\/\"><span class=\"s20\">Legalis<\/span><\/a><\/div>\n<div>42. <a href=\"https:\/\/www.legifrance.gouv.fr\/\"><span class=\"s20\">Legifrance<\/span><\/a><\/div>\n<div>43. <a href=\"https:\/\/www.lex-electronica.org\/\"><span class=\"s20\">Lex<\/span> <span class=\"s20\">Electronica<\/span><\/a><\/div>\n<div>44. <a href=\"http:\/\/kenyalaw.org\/kenyalawblog\/\"><span class=\"s15\">Kenya Law<\/span><\/a><\/div>\n<div>45. <a href=\"http:\/\/www.loc.gov\/law\/\"><span class=\"s15\">Law Library of Congress<\/span><\/a><\/div>\n<div>46. <a href=\"https:\/\/justice.belgium.be\/fr\/ordre_judiciaire\/cours_et_tribunaux\/cour_de_cassation\/documents\/libercas\"><span class=\"s15\">LiberCas<\/span><span class=\"s15\"> (Belgique service public justice)<\/span><\/a><\/div>\n<div>47. <a href=\"http:\/\/www.myhq.com\/public\/b\/l\/blawgs\/\"><span class=\"s15\">myhq<\/span> <span class=\"s15\">blawgs<\/span><\/a><\/div>\n<div>48. <a href=\"http:\/\/www.nber.org\/\"><span class=\"s15\">National Bureau of Economic Research <\/span><\/a><\/div>\n<div>49. <a href=\"http:\/\/www.cdmo.univ-nantes.fr\/41958401\/0\/fiche___pagelibre\/&amp;RH=1380007571599\"><span class=\"s15\">Neptunus<\/span><span class=\"s15\">, e-revue (Nantes)<\/span><\/a><\/div>\n<div>50. <a href=\"http:\/\/www.nlipw.com\/\"><span class=\"s18\">Nigerian Law Intellectual property Watch<\/span><\/a><\/div>\n<div>51. <a href=\"http:\/\/nopr.niscair.res.in\/handle\/123456789\/45\"><span class=\"s15\">Niscair<\/span><\/a><\/div>\n<div>52. <a href=\"http:\/\/www.ohada.com\/\"><span class=\"s9\">Ohada <\/span><span class=\"s9\">com<\/span><\/a><\/div>\n<div class=\"s16\">53. <a href=\"http:\/\/www.ohada.org\/index.php\/fr\/\"><span class=\"s9\">Ohada <\/span><span class=\"s9\">org<\/span><\/a><span class=\"s21\"> (site officiel de l\u2019Ohada)<\/span><\/div>\n<div>54. <a href=\"http:\/\/stl.pku.edu.cn\/academics\/peking-university-transnational-law-review\/\"><span class=\"s22\">Pekin University Transnational Law Review <\/span><\/a><\/div>\n<div class=\"s16\">55. <a href=\"http:\/\/law.nwu.ac.za\/per\"><span class=\"s20\">PER\/PER<\/span><\/a> <span class=\"s23\">(South Africa Potchefstroom Electronic Law Journal)<\/span><\/div>\n<div>56. <a href=\"https:\/\/seer.imed.edu.br\/index.php\/revistadedireito\"><span class=\"s15\">Revista<\/span> <span class=\"s15\">brasileira<\/span><span class=\"s15\"> de <\/span><span class=\"s15\">direito<\/span><\/a><\/div>\n<div>57. <a href=\"https:\/\/www.publicacoesacademicas.uniceub.br\/rdi\"><span class=\"s15\">Revista<\/span><span class=\"s15\"> do <\/span><span class=\"s15\">Direito<\/span> <span class=\"s15\">internacional<\/span><\/a><\/div>\n<div>58. <a href=\"http:\/\/www2.senado.leg.br\/bdsf\/item\/id\/22\"><span class=\"s15\">Revista<\/span><span class=\"s15\"> de <\/span><span class=\"s15\">Informa\u00e7\u00e3o<\/span> <span class=\"s15\">Legislativa<\/span><\/a><\/div>\n<div>59. <a href=\"http:\/\/www.reei.org\/\"><span class=\"s15\">Revista<\/span> <span class=\"s15\">Electr\u00f3nica<\/span> <span class=\"s15\">de <\/span><span class=\"s15\">Estudios<\/span> <span class=\"s15\">Internacionales<\/span><\/a><\/div>\n<div>60. <a href=\"https:\/\/revistas-colaboracion.juridicas.unam.mx\/index.php\/comercial\"><span class=\"s15\">Revista Latinoamericana de Derecho Comercial Internacional<\/span><\/a><\/div>\n<div>61. <a href=\"http:\/\/revistas.uexternado.edu.co\/index.php\/propin\"><span class=\"s15\">Revista<\/span><span class=\"s15\"> la <\/span><span class=\"s15\">propriedad<\/span> <span class=\"s15\">inmaterial<\/span><\/a><\/div>\n<div class=\"s16\">62. <span class=\"s17\">Revista<\/span><span class=\"s17\"> de <\/span><span class=\"s17\">Processo<\/span><\/div>\n<div>63. <a href=\"http:\/\/www.derechocomercial.edu.uy\/Publicaciones.htm\"><span class=\"s15\">Revista<\/span><span class=\"s15\"> Virtual de Derecho <\/span><span class=\"s15\">Comercial<\/span><\/a><\/div>\n<div>64. <a href=\"http:\/\/www.henricapitant.org\/revue\/fr\"><span class=\"s15\">Revue Henri <\/span><span class=\"s15\">Capitant<\/span><\/a><\/div>\n<div>65. <a href=\"http:\/\/www.association-afpi.org\/presse\/index.php\/RFPI\/index\"><span class=\"s9\">Revue francophone de la propri\u00e9t\u00e9 intellectuelle <\/span><\/a><\/div>\n<div>66. <a href=\"http:\/\/www.russianlawjournal.org\/\"><span class=\"s15\">Russian Law Journal<\/span><\/a><\/div>\n<div>67. <a href=\"http:\/\/www.sentinelle-droit-international.fr\/\"><span class=\"s15\">Sentinelle, P\u00f4le information de droit international, Bulletin<\/span><\/a><\/div>\n<div>68. <a href=\"http:\/\/www.singaporelawreview.com\/\"><span class=\"s18\">Singapore Law Review<\/span><\/a><\/div>\n<div>69. <a href=\"http:\/\/law.nus.edu.sg\/sjls\/index.html\"><span class=\"s15\">Singapore Journal of <\/span><span class=\"s15\">Legal<\/span> <span class=\"s15\">Studies<\/span><\/a><\/div>\n<div class=\"s16\">70. <a href=\"http:\/\/www.ssrn.com\/en\/\"><span class=\"s15\">SSRN<\/span><\/a> <span class=\"s17\">Social Science Research Network<\/span><span class=\"s17\"> \u00a0<\/span><\/div>\n<div>71. <a href=\"http:\/\/www.stanfordlawreview.org\/\"><span class=\"s15\">Stanford Law Review<\/span><\/a><\/div>\n<div>72. <a href=\"https:\/\/ssl.editionsthemis.com\/revue\/\"><span class=\"s15\">Th\u00e9mis (revue juridique, Qu\u00e9bec)<\/span><\/a><\/div>\n<div class=\"s16\">73. <span class=\"s17\">Tribunal I<\/span><span class=\"s17\">nternational du <\/span><span class=\"s17\">Droit de la M<\/span><span class=\"s17\">er<\/span> <a href=\"https:\/\/www.itlos.org\/\"><span class=\"s15\">Itlos<\/span><\/a><\/div>\n<div>74. <a href=\"http:\/\/www.uclalawreview.org\/\"><span class=\"s15\">UCLA Law Review<\/span><\/a><\/div>\n<div>75. <a href=\"https:\/\/www.utrechtlawreview.org\/\"><span class=\"s15\">Utrecht Law Review<\/span><\/a><\/div>\n<div>76. <a href=\"https:\/\/www.journals.elsevier.com\/world-development\/\"><span class=\"s15\">World Development<\/span><\/a><\/div>\n<div>77. <a href=\"http:\/\/www.xinhuanet.com\/english\/africa\/\"><span class=\"s15\">XInHua<\/span><span class=\"s15\"> Net <\/span><span class=\"s15\">Africa<\/span><\/a><\/div>\n<div>78. <a href=\"http:\/\/www.xinhuanet.com\/english\/home.htm\"><span class=\"s15\">XinHua<\/span><span class=\"s15\"> net in English<\/span><\/a><\/div>\n<div>79. <a href=\"http:\/\/www.yalelawjournal.org\/\"><span class=\"s15\">Yale Law Journal<\/span><\/a><\/div>\n<p class=\"s3\">\n","protected":false},"excerpt":{"rendered":"<p>NDLR \u2013 Pri\u00e8re de nous informer du moindre disfonctionnement que vous pourriez constater \u00e0 l\u2019adresse\u00a0: france.ohada.droit@gmail.com Vous pouvez \u00e9galement nous sugg\u00e9rer des sites en libre acc\u00e8s, d\u2019int\u00e9r\u00eatpour un lectorat majoritairement d\u2019Afrique francophone. Nous vous proposons\u00a0: \u2022 une liste g\u00e9n\u00e9rale des sites par ordre ABC\u00a0; \u2713 une liste de sites de culture et\/ou langue francophone\u00a0; \u2713 une liste de site de culture anglophone\u00a0et\/ou langue\u00a0; \u2713 et une liste de sites concernant les autres<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sites juridiques et financiers, en libre acc\u00e8s - France Ohada Droit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sites juridiques et financiers, en libre acc\u00e8s - France Ohada Droit\" \/>\n<meta property=\"og:description\" content=\"NDLR \u2013 Pri\u00e8re de nous informer du moindre disfonctionnement que vous pourriez constater \u00e0 l\u2019adresse\u00a0: france.ohada.droit@gmail.com Vous pouvez \u00e9galement nous sugg\u00e9rer des sites en libre acc\u00e8s, d\u2019int\u00e9r\u00eatpour un lectorat majoritairement d\u2019Afrique francophone. Nous vous proposons\u00a0: \u2022 une liste g\u00e9n\u00e9rale des sites par ordre ABC\u00a0; \u2713 une liste de sites de culture et\/ou langue francophone\u00a0; \u2713 une liste de site de culture anglophone\u00a0et\/ou langue\u00a0; \u2713 et une liste de sites concernant les autres [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/\" \/>\n<meta property=\"og:site_name\" content=\"France Ohada Droit\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-11T02:47:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/france-ohada-droit.com\/#website\",\"url\":\"https:\/\/france-ohada-droit.com\/\",\"name\":\"France Ohada Droit\",\"description\":\"Article de droit\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/france-ohada-droit.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/#webpage\",\"url\":\"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/\",\"name\":\"Sites juridiques et financiers, en libre acc\u00e8s - France Ohada Droit\",\"isPartOf\":{\"@id\":\"https:\/\/france-ohada-droit.com\/#website\"},\"datePublished\":\"2019-02-11T13:10:20+00:00\",\"dateModified\":\"2020-08-11T02:47:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/france-ohada-droit.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sites juridiques et financiers, en libre acc\u00e8s\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sites juridiques et financiers, en libre acc\u00e8s - France Ohada Droit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/","og_locale":"fr_FR","og_type":"article","og_title":"Sites juridiques et financiers, en libre acc\u00e8s - France Ohada Droit","og_description":"NDLR \u2013 Pri\u00e8re de nous informer du moindre disfonctionnement que vous pourriez constater \u00e0 l\u2019adresse\u00a0: france.ohada.droit@gmail.com Vous pouvez \u00e9galement nous sugg\u00e9rer des sites en libre acc\u00e8s, d\u2019int\u00e9r\u00eatpour un lectorat majoritairement d\u2019Afrique francophone. Nous vous proposons\u00a0: \u2022 une liste g\u00e9n\u00e9rale des sites par ordre ABC\u00a0; \u2713 une liste de sites de culture et\/ou langue francophone\u00a0; \u2713 une liste de site de culture anglophone\u00a0et\/ou langue\u00a0; \u2713 et une liste de sites concernant les autres [\u2026]","og_url":"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/","og_site_name":"France Ohada Droit","article_modified_time":"2020-08-11T02:47:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/france-ohada-droit.com\/#website","url":"https:\/\/france-ohada-droit.com\/","name":"France Ohada Droit","description":"Article de droit","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/france-ohada-droit.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/#webpage","url":"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/","name":"Sites juridiques et financiers, en libre acc\u00e8s - France Ohada Droit","isPartOf":{"@id":"https:\/\/france-ohada-droit.com\/#website"},"datePublished":"2019-02-11T13:10:20+00:00","dateModified":"2020-08-11T02:47:39+00:00","breadcrumb":{"@id":"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/france-ohada-droit.com\/index.php\/sites-juridiques-et-financiers-en-libre-acces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/france-ohada-droit.com\/"},{"@type":"ListItem","position":2,"name":"Sites juridiques et financiers, en libre acc\u00e8s"}]}]}},"_links":{"self":[{"href":"https:\/\/france-ohada-droit.com\/index.php\/wp-json\/wp\/v2\/pages\/1428"}],"collection":[{"href":"https:\/\/france-ohada-droit.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/france-ohada-droit.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/france-ohada-droit.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/france-ohada-droit.com\/index.php\/wp-json\/wp\/v2\/comments?post=1428"}],"version-history":[{"count":2,"href":"https:\/\/france-ohada-droit.com\/index.php\/wp-json\/wp\/v2\/pages\/1428\/revisions"}],"predecessor-version":[{"id":2072,"href":"https:\/\/france-ohada-droit.com\/index.php\/wp-json\/wp\/v2\/pages\/1428\/revisions\/2072"}],"wp:attachment":[{"href":"https:\/\/france-ohada-droit.com\/index.php\/wp-json\/wp\/v2\/media?parent=1428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}